{"id":14365,"date":"2023-05-11T08:43:51","date_gmt":"2023-05-11T08:43:51","guid":{"rendered":"https:\/\/alfredopolti-cyon.local\/?post_type=usecases&#038;p=14365"},"modified":"2023-05-17T09:09:40","modified_gmt":"2023-05-17T09:09:40","slug":"stairs","status":"publish","type":"usecases","link":"https:\/\/alfredopolti.ch\/en\/anwendungsbereich\/stairs\/","title":{"rendered":"Stairs"},"content":{"rendered":"    <section class=\"eoss_fullwidth_image eoss_fullwidth\" style=\"background-image: url(https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-057.jpg\">\n\n    <\/section>\n\n    \n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<section class=\"eoss_two_color_header eoss_header_left\">\n    <span class=\"eoss_two_color_header_red\">Stairs<\/span>\n    <span class=\"eoss_two_color_header_gray\">Taking ambience to the next level <\/span>\n<\/section>\n    \n\n\n<p class=\"wp-block-paragraph\">With stairs made of gneiss, differences in height can be overcome with confidence and style. Inside as well as outside they provide connecting elements for an appealing ambience without functionality stopping halfway.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<section class=\"eoss_two_color_header eoss_header_left\">\n    <span class=\"eoss_two_color_header_red\">A clear path<\/span>\n    <span class=\"eoss_two_color_header_gray\">External stairs<\/span>\n<\/section>\n    \n\n\n<p class=\"wp-block-paragraph\">Whether beginning or end: stairs always tell a story. With them, the way up or down opens up in any weather. You can choose from natural split or blasted (sand-blasted, flamed, bush-hammered) treads or block steps with various visible edge finishes.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-4 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-quadrat\"><a href=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-130-500x500.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" data-id=\"3057\" src=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-130-500x500.jpg\" alt=\"\" class=\"wp-image-3057\" srcset=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-130-500x500.jpg 500w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-130-300x300.jpg 300w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-130-100x100.jpg 100w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-130-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-quadrat\"><a href=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-041-500x500.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" data-id=\"3018\" src=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-041-500x500.jpg\" alt=\"\" class=\"wp-image-3018\" srcset=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-041-500x500.jpg 500w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-041-300x300.jpg 300w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-041-100x100.jpg 100w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-041-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-quadrat\"><a href=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-055-500x500.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" data-id=\"3012\" src=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-055-500x500.jpg\" alt=\"\" class=\"wp-image-3012\" srcset=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-055-500x500.jpg 500w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-055-300x300.jpg 300w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-055-100x100.jpg 100w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-055-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-quadrat\"><a href=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-122-500x500.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" data-id=\"2958\" src=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-122-500x500.jpg\" alt=\"\" class=\"wp-image-2958\" srcset=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-122-500x500.jpg 500w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-122-300x300.jpg 300w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-122-100x100.jpg 100w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-122-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-quadrat\"><a href=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-040-500x500.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" data-id=\"2976\" src=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-040-500x500.jpg\" alt=\"\" class=\"wp-image-2976\" srcset=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-040-500x500.jpg 500w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-040-300x300.jpg 300w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-040-100x100.jpg 100w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-040-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-quadrat\"><a href=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-184-500x500.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" data-id=\"2856\" src=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-184-500x500.jpg\" alt=\"\" class=\"wp-image-2856\" srcset=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-184-500x500.jpg 500w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-184-scaled-300x300.jpg 300w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-184-scaled-100x100.jpg 100w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-184-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-quadrat\"><a href=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-220-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1706\" height=\"2560\" data-id=\"2826\" src=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-220-scaled.jpg\" alt=\"\" class=\"wp-image-2826\" srcset=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-220-scaled.jpg 1706w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-220-scaled-600x900.jpg 600w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-220-200x300.jpg 200w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-220-682x1024.jpg 682w\" sizes=\"auto, (max-width: 1706px) 100vw, 1706px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-quadrat\"><a href=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-189@p-500x500.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" data-id=\"2397\" src=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-189@p-500x500.jpg\" alt=\"\" class=\"wp-image-2397\" srcset=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-189@p-500x500.jpg 500w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-189@p-300x300.jpg 300w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-189@p-100x100.jpg 100w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-189@p-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-quadrat\"><a href=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-150@p-500x500.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" data-id=\"2430\" src=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-150@p-500x500.jpg\" alt=\"\" class=\"wp-image-2430\" srcset=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-150@p-500x500.jpg 500w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-150@p-300x300.jpg 300w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-150@p-100x100.jpg 100w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-150@p-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-quadrat\"><a href=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-089@p-500x500.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" data-id=\"2514\" src=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-089@p-500x500.jpg\" alt=\"\" class=\"wp-image-2514\" srcset=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-089@p-500x500.jpg 500w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-089@p-300x300.jpg 300w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-089@p-100x100.jpg 100w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-089@p-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-quadrat\"><a href=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-228-500x500.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" data-id=\"2580\" src=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-228-500x500.jpg\" alt=\"\" class=\"wp-image-2580\" srcset=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-228-500x500.jpg 500w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-228-scaled-300x300.jpg 300w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-228-scaled-100x100.jpg 100w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-228-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-quadrat\"><a href=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-211-500x500.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" data-id=\"2631\" src=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-211-500x500.jpg\" alt=\"\" class=\"wp-image-2631\" srcset=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-211-500x500.jpg 500w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-211-300x300.jpg 300w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-211-100x100.jpg 100w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-211-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-quadrat\"><a href=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-200-500x500.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" data-id=\"2583\" src=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-200-500x500.jpg\" alt=\"\" class=\"wp-image-2583\" srcset=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-200-500x500.jpg 500w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-200-scaled-300x300.jpg 300w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-200-scaled-100x100.jpg 100w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-200-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-quadrat\"><a href=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-234-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1706\" data-id=\"2823\" src=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-234-scaled.jpg\" alt=\"\" class=\"wp-image-2823\" srcset=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-234-scaled.jpg 2560w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-234-scaled-600x400.jpg 600w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-234-300x200.jpg 300w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-quadrat\"><a href=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-218-500x500.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" data-id=\"2838\" src=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-218-500x500.jpg\" alt=\"\" class=\"wp-image-2838\" srcset=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-218-500x500.jpg 500w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-218-scaled-300x300.jpg 300w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-218-scaled-100x100.jpg 100w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-218-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-quadrat\"><a href=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-087@p-500x500.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" data-id=\"2970\" src=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-087@p-500x500.jpg\" alt=\"\" class=\"wp-image-2970\" srcset=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-087@p-500x500.jpg 500w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-087@p-300x300.jpg 300w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-087@p-100x100.jpg 100w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/aussen-treppen_05A-087@p-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<section class=\"eoss_two_color_header eoss_header_left\">\n    <span class=\"eoss_two_color_header_red\">Connection with safety<\/span>\n    <span class=\"eoss_two_color_header_gray\">Internal stairs<\/span>\n<\/section>\n    \n\n\n<p class=\"wp-block-paragraph\">Gneiss creates a connection over several steps, and every careful detail in the processing makes the stone a source of safety. Step slabs are available in various surface and visible edge finishes, the dimensions and thicknesses are cut individually according to customer requirements.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-4 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-quadrat\"><a href=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-020@p-500x500.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" data-id=\"3210\" src=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-020@p-500x500.jpg\" alt=\"\" class=\"wp-image-3210\" srcset=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-020@p-500x500.jpg 500w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-020@p-300x300.jpg 300w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-020@p-100x100.jpg 100w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-020@p-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-quadrat\"><a href=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-013-500x500.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" data-id=\"3213\" src=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-013-500x500.jpg\" alt=\"\" class=\"wp-image-3213\" srcset=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-013-500x500.jpg 500w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-013-300x300.jpg 300w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-013-100x100.jpg 100w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-013-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-quadrat\"><a href=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-003-500x500.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" data-id=\"3174\" src=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-003-500x500.jpg\" alt=\"\" class=\"wp-image-3174\" srcset=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-003-500x500.jpg 500w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-003-300x300.jpg 300w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-003-100x100.jpg 100w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-003-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-quadrat\"><a href=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-001@p-500x500.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" data-id=\"3234\" src=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-001@p-500x500.jpg\" alt=\"\" class=\"wp-image-3234\" srcset=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-001@p-500x500.jpg 500w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-001@p-300x300.jpg 300w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-001@p-100x100.jpg 100w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-001@p-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-quadrat\"><a href=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-024@p-500x500.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" data-id=\"3180\" src=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-024@p-500x500.jpg\" alt=\"\" class=\"wp-image-3180\" srcset=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-024@p-500x500.jpg 500w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-024@p-300x300.jpg 300w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-024@p-100x100.jpg 100w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-024@p-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-quadrat\"><a href=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-016-500x500.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" data-id=\"3171\" src=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-016-500x500.jpg\" alt=\"\" class=\"wp-image-3171\" srcset=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-016-500x500.jpg 500w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-016-300x300.jpg 300w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-016-100x100.jpg 100w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-016-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-quadrat\"><a href=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-033@p-500x500.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" data-id=\"3147\" src=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-033@p-500x500.jpg\" alt=\"\" class=\"wp-image-3147\" srcset=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-033@p-500x500.jpg 500w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-033@p-300x300.jpg 300w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-033@p-100x100.jpg 100w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-033@p-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-quadrat\"><a href=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-030@p-500x500.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" data-id=\"3117\" src=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-030@p-500x500.jpg\" alt=\"\" class=\"wp-image-3117\" srcset=\"https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-030@p-500x500.jpg 500w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-030@p-300x300.jpg 300w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-030@p-100x100.jpg 100w, https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/08\/innen-treppen_05B-030@p-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n    <section class=\"eoss_grey_accordion eoss_accordion_element eoss_fullwidth eoss_grey_background\">\n        <article class=\"eoss_contentwidth\">\n            <header class=\"eoss_accordion_control\">\n                <h3>Recommended surfaces<\/h3>\n                <p>We show you which surfaces and visible edge finishes are suitable for exterior floors. Benefit from our many years of experience.<\/p>\n            <\/header>\n            <main>\n                <div class=\"acf-innerblocks-container\">\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n    <section class=\"eoss_textures\">\n            <\/section>\n\n\n<\/div>\n            <\/main>\n            <div class=\"eoss_accordion_control eoss_accordion_control_arrow\"><\/div>\n        <\/article>\n    <\/section>\n    \n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n    <section class=\"eoss_references eoss_contentwidth eoss_filter_container\">\n\n            <article class=\"eoss_single_reference eoss_single_filter_object\" key=\"facciate-e-tetti-en\">\n            <section class=\"eoss_single_reference_text\">\n                <h3>BNB AI CAV CALANCA \/ <span class=\"eoss_references_location\"><\/span><\/h3>\n                                <a class=\"eoss_reference_readmore\" href=\"https:\/\/alfredopolti.ch\/en\/referenzen\/bnb-ai-cav-calanca-2\/\">Read<\/a>\n            <\/section>\n            <div class=\"eoss_reference_image\" style=\"background-image: url('https:\/\/alfredopolti.ch\/wp-content\/uploads\/2021\/10\/15_NeuesDach-scaled.jpg');\"><\/div>\n\n        <\/article>\n            <\/section>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<article class=\"eoss_suppliers\">\n    <section class=\"eoss_two_color_header\">\n        <span class=\"eoss_two_color_header_red\"><\/span>\n        <span class=\"eoss_two_color_header_gray\"><\/span>\n\n    <\/section>\n    <p>\n            <\/p>\n    <a class=\"eoss_button\" href=\"https:\/\/alfredopolti.ch\/en\/startseite\/fachhaendlersuche\/\"><span>Search for a dealer<\/span><\/a>\n<!--    <ul class=\"eoss_suppliers_list\">-->\n<!--        --><!--            <li class=\"eoss_suppliers_list_single\">-->\n<!--                <img decoding=\"async\" src=\"--><!--\">-->\n<!--                <div>-->\n<!--                    <span class=\"eoss_suppliers_list_single_name\">--><!--<\/span>-->\n<!--                    <span class=\"eoss_suppliers_list_single_address\">--><!--, --><!--<\/span>-->\n<!--                    <a href=\"--><!--\" target=\"_blank\">Website<\/a>-->\n<!---->\n<!--                <\/div>-->\n<!--            <\/li>-->\n<!---->\n<!--            --><!---->\n<!---->\n<!---->\n<!--    <\/ul>-->\n\n<\/article>\n\n","protected":false},"author":274,"featured_media":2959,"template":"","subjects_usecases":[],"class_list":["post-14365","usecases","type-usecases","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/alfredopolti.ch\/en\/wp-json\/wp\/v2\/usecases\/14365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alfredopolti.ch\/en\/wp-json\/wp\/v2\/usecases"}],"about":[{"href":"https:\/\/alfredopolti.ch\/en\/wp-json\/wp\/v2\/types\/usecases"}],"author":[{"embeddable":true,"href":"https:\/\/alfredopolti.ch\/en\/wp-json\/wp\/v2\/users\/274"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alfredopolti.ch\/en\/wp-json\/wp\/v2\/media\/2959"}],"wp:attachment":[{"href":"https:\/\/alfredopolti.ch\/en\/wp-json\/wp\/v2\/media?parent=14365"}],"wp:term":[{"taxonomy":"subjects_usecases","embeddable":true,"href":"https:\/\/alfredopolti.ch\/en\/wp-json\/wp\/v2\/subjects_usecases?post=14365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}